{"id":85,"count":17,"description":"Jugar desde tu celular Android en tu casa de apuestas favorita nunca ha sido tan f\u00e1cil. Solo tienes que descargarte la aplicaci\u00f3n desde la tienda oficial de Google o desde la propia p\u00e1gina web de la casa de apuestas para poder apostar desde donde quieras gracias a la app.\r\n\r\nAdem\u00e1s, todas las casas de apuestas que encontrar\u00e1s aqu\u00ed tienen su web adaptada a sistemas Android para que puedas jugar sin necesidad de descargar la app.","link":"https:\/\/casasdeapuestas.bet\/cl\/app\/android\/","name":"Android","slug":"android","taxonomy":"software","parent":0,"meta":[],"acf":[],"_links":{"self":[{"href":"https:\/\/casasdeapuestas.bet\/cl\/wp-json\/wp\/v2\/software\/85","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/casasdeapuestas.bet\/cl\/wp-json\/wp\/v2\/software"}],"about":[{"href":"https:\/\/casasdeapuestas.bet\/cl\/wp-json\/wp\/v2\/taxonomies\/software"}],"wp:post_type":[{"href":"https:\/\/casasdeapuestas.bet\/cl\/wp-json\/wp\/v2\/casino?software=85"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}